{"id":432,"date":"2018-05-27T17:39:44","date_gmt":"2018-05-27T15:39:44","guid":{"rendered":"https:\/\/gaestehauscosima.de\/impressum\/"},"modified":"2018-09-11T15:29:13","modified_gmt":"2018-09-11T13:29:13","slug":"impressum","status":"publish","type":"page","link":"https:\/\/www.gaestehauscosima.de\/fr\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"<h2>Angaben gem\u00e4\u00df \u00a7 5 TMG:<\/h2>\n<p>Cosima G\u00f6dde<br \/>\nG\u00e4stehaus Cosima<br \/>\nKuhlertstra\u00dfe 71<br \/>\n52525 Heinsberg<\/p>\n<h2>Kontakt:<\/h2>\n<p>Telefon: +49 (0) 2452 930600<br \/>\nTelefax: +49 (0) 2452 930700<br \/>\nE-Mail: info@gaestehauscosima.de<\/p>\n<h2>Umsatzsteuer:<\/h2>\n<p>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727 a Umsatzsteuergesetz:<br \/>\n99 805 647 133<\/p>\n<h2>Streitschlichtung<\/h2>\n<p>Hinweis zur Online-Streitbeilegung gem\u00e4\u00df Art. 14 Abs. 1 ODR-VO: Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit: <a href=\"https:\/\/ec.europa.eu\/consumers\/odr\" target=\"_blank\" rel=\"noopener\">https:\/\/ec.europa.eu\/consumers\/odr<\/a><br \/>\nUnsere E-Mail-Adresse finden Sie oben im Impressum.<\/p>\n<p>Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p>\n<h2>Haftung f\u00fcr Inhalte<\/h2>\n<p>Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<\/p>\n<p>Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p>\n<h2>Haftung f\u00fcr Links<\/h2>\n<p>Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<\/p>\n<p>Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p>\n<h2>Urheberrecht<\/h2>\n<p>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet.<\/p>\n<p>Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<\/p>\n<p>Quelle: <a href=\"https:\/\/www.e-recht24.de\/impressum-generator.html\">https:\/\/www.e-recht24.de\/impressum- generator.html<\/a><\/p>\n<p>Bildnachweis:<\/p>\n<p>Nato-Airbase<br \/>\n<a href=\"https:\/\/commons.wikimedia.org\/wiki\/User:J._Patrick_Fischer\">J. Patrick Fischer<\/a>, <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:20170313_AWACS-09.jpg\">20170313 AWACS-09<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/legalcode\" rel=\"license\">CC BY-SA 4.0<\/a><\/p>\n<p>Selfkantbahn:<br \/>\n<a href=\"https:\/\/selfkantbahn.de\">https:\/\/selfkantbahn.de<\/a> (Markus Kaiser)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angaben gem\u00e4\u00df \u00a7 5 TMG: Cosima G\u00f6dde G\u00e4stehaus Cosima Kuhlertstra\u00dfe 71 52525 Heinsberg Kontakt: Telefon: +49 (0) 2452 930600 Telefax: +49 (0) 2452 930700 E-Mail: info@gaestehauscosima.de Umsatzsteuer: Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727 a Umsatzsteuergesetz: 99 805 647 133 Streitschlichtung Hinweis zur Online-Streitbeilegung gem\u00e4\u00df Art. 14 Abs. 1 ODR-VO: Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS)<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/pages\/432"}],"collection":[{"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/comments?post=432"}],"version-history":[{"count":6,"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/pages\/432\/revisions"}],"predecessor-version":[{"id":1109,"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/pages\/432\/revisions\/1109"}],"wp:attachment":[{"href":"https:\/\/www.gaestehauscosima.de\/fr\/wp-json\/wp\/v2\/media?parent=432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}